{"id":2083,"count":1,"description":"","link":"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/","name":"secondary schools","slug":"secondary-schools","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>secondary schools archivos - Educational Evidence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"secondary schools archivos - Educational Evidence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/\" \/>\n<meta property=\"og:site_name\" content=\"Educational Evidence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/tag\\\/secondary-schools\\\/\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/tag\\\/secondary-schools\\\/\",\"name\":\"secondary schools archivos - Educational Evidence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/tag\\\/secondary-schools\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/tag\\\/secondary-schools\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"secondary schools\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/\",\"name\":\"Educational Evidence\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/#organization\",\"name\":\"Educational Evidence\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/educational_evidence_logo_horitzontal_blanc_negatiu.png\",\"contentUrl\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/educational_evidence_logo_horitzontal_blanc_negatiu.png\",\"width\":3508,\"height\":1090,\"caption\":\"Educational Evidence\"},\"image\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"secondary schools archivos - Educational Evidence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/","og_locale":"en_US","og_type":"article","og_title":"secondary schools archivos - Educational Evidence","og_url":"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/","og_site_name":"Educational Evidence","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/","url":"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/","name":"secondary schools archivos - Educational Evidence","isPartOf":{"@id":"https:\/\/educationalevidence.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/educationalevidence.com\/en\/tag\/secondary-schools\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/educationalevidence.com\/en\/"},{"@type":"ListItem","position":2,"name":"secondary schools"}]},{"@type":"WebSite","@id":"https:\/\/educationalevidence.com\/en\/#website","url":"https:\/\/educationalevidence.com\/en\/","name":"Educational Evidence","description":"","publisher":{"@id":"https:\/\/educationalevidence.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/educationalevidence.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/educationalevidence.com\/en\/#organization","name":"Educational Evidence","url":"https:\/\/educationalevidence.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/educationalevidence.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2023\/07\/educational_evidence_logo_horitzontal_blanc_negatiu.png","contentUrl":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2023\/07\/educational_evidence_logo_horitzontal_blanc_negatiu.png","width":3508,"height":1090,"caption":"Educational Evidence"},"image":{"@id":"https:\/\/educationalevidence.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/educationalevidence.com\/en\/wp-json\/wp\/v2\/tags\/2083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educationalevidence.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/educationalevidence.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/educationalevidence.com\/en\/wp-json\/wp\/v2\/posts?tags=2083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}