{"id":1075,"count":1,"description":"","link":"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/","name":"el diamant de Villasola","slug":"el-diamant-de-villasola","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>el diamant de Villasola archivos - Educational Evidence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"el diamant de Villasola archivos - Educational Evidence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/\" \/>\n<meta property=\"og:site_name\" content=\"Educational Evidence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/tag\\\/el-diamant-de-villasola\\\/\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/tag\\\/el-diamant-de-villasola\\\/\",\"name\":\"el diamant de Villasola archivos - Educational Evidence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/tag\\\/el-diamant-de-villasola\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/tag\\\/el-diamant-de-villasola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"el diamant de Villasola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/\",\"name\":\"Educational Evidence\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#organization\",\"name\":\"Educational Evidence\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/educational_evidence_logo_horitzontal_blanc_negatiu.png\",\"contentUrl\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/educational_evidence_logo_horitzontal_blanc_negatiu.png\",\"width\":3508,\"height\":1090,\"caption\":\"Educational Evidence\"},\"image\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"el diamant de Villasola archivos - Educational Evidence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/","og_locale":"ca_ES","og_type":"article","og_title":"el diamant de Villasola archivos - Educational Evidence","og_url":"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/","og_site_name":"Educational Evidence","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/","url":"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/","name":"el diamant de Villasola archivos - Educational Evidence","isPartOf":{"@id":"https:\/\/educationalevidence.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/educationalevidence.com\/ca\/tag\/el-diamant-de-villasola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/educationalevidence.com\/ca\/"},{"@type":"ListItem","position":2,"name":"el diamant de Villasola"}]},{"@type":"WebSite","@id":"https:\/\/educationalevidence.com\/ca\/#website","url":"https:\/\/educationalevidence.com\/ca\/","name":"Educational Evidence","description":"","publisher":{"@id":"https:\/\/educationalevidence.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/educationalevidence.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/educationalevidence.com\/ca\/#organization","name":"Educational Evidence","url":"https:\/\/educationalevidence.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/educationalevidence.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2023\/07\/educational_evidence_logo_horitzontal_blanc_negatiu.png","contentUrl":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2023\/07\/educational_evidence_logo_horitzontal_blanc_negatiu.png","width":3508,"height":1090,"caption":"Educational Evidence"},"image":{"@id":"https:\/\/educationalevidence.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/tags\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/posts?tags=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}