{"id":22499,"date":"2024-11-28T09:22:17","date_gmt":"2024-11-28T08:22:17","guid":{"rendered":"https:\/\/educationalevidence.com\/?p=22499"},"modified":"2024-11-29T09:31:07","modified_gmt":"2024-11-29T08:31:07","slug":"maieutica-i-merda-de-filosofia","status":"publish","type":"post","link":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/","title":{"rendered":"Mai\u00e8utica (I): Merda de filosofia"},"content":{"rendered":"<blockquote><p><strong>FORA DE LLOC<\/strong><\/p><\/blockquote>\n<h1>Mai\u00e8utica (I): Merda de filosofia<\/h1>\n<figure id=\"attachment_22525\" aria-describedby=\"caption-attachment-22525\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-22525\" src=\"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg\" alt=\"\" width=\"720\" height=\"638\" srcset=\"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg 720w, https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop-300x266.jpg 300w, https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop-372x330.jpg 372w, https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop-203x180.jpg 203w, https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop-80x70.jpg 80w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><figcaption id=\"caption-attachment-22525\" class=\"wp-caption-text\">El militar aten\u00e8s Alcib\u00edades i S\u00f2crates. \/ Marcello Bacciarelli \/ Wikimedia.<\/figcaption><\/figure>\n<p><a style=\"display: inline-block;\" href=\"https:\/\/creativecommons.org\/licenses\/by-nc-nd\/4.0\/deed.ca\" target=\"_blank\" rel=\"license noopener noreferrer\">Llic\u00e8ncia Creative Commons<img decoding=\"async\" style=\"height: 22px!important; margin-left: 3px; vertical-align: text-bottom;\" src=\"https:\/\/mirrors.creativecommons.org\/presskit\/icons\/cc.svg?ref=chooser-v1\" \/><img decoding=\"async\" style=\"height: 22px!important; margin-left: 3px; vertical-align: text-bottom;\" src=\"https:\/\/mirrors.creativecommons.org\/presskit\/icons\/by.svg?ref=chooser-v1\" \/><img decoding=\"async\" style=\"height: 22px!important; margin-left: 3px; vertical-align: text-bottom;\" src=\"https:\/\/mirrors.creativecommons.org\/presskit\/icons\/nc.svg?ref=chooser-v1\" \/><img decoding=\"async\" style=\"height: 22px!important; margin-left: 3px; vertical-align: text-bottom;\" src=\"https:\/\/mirrors.creativecommons.org\/presskit\/icons\/nd.svg?ref=chooser-v1\" \/><\/a><\/p>\n<p><strong><img decoding=\"async\" class=\"alignleft wp-image-20530\" src=\"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/10\/Javier-Rodrigo-150x150.jpg\" sizes=\"(max-width: 70px) 100vw, 70px\" srcset=\"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/10\/Javier-Rodrigo-150x150.jpg 150w, https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/10\/Javier-Rodrigo-298x300.jpg 298w, https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/10\/Javier-Rodrigo.jpg 440w\" alt=\"\" width=\"70\" height=\"70\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Javier Rodrigo<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La <strong>mai\u00e8utica<\/strong> \u00e9s di\u00e0leg. El segon acte del <strong>m\u00e8tode socr\u00e0tic<\/strong> d\u2019aprenentatge: el que genera el coneixement, despr\u00e9s d\u2019un primer moment de fingida ignor\u00e0ncia per part del mestre, mitjan\u00e7ant la realitzaci\u00f3 de les preguntes correctes que estimulin la recerca de les respostes dins seu. No \u00e9s un m\u00e8tode unidireccional, sin\u00f3 que la saviesa s&#8217;extreu de dins dels caps de l&#8217;alumnat i es verbalitza en posar-lo davant dels dubtes i els interrogants adequats. La <strong>mai\u00e8utica \u00e9s, per a S\u00f2crates, la llevadora de la saviesa<\/strong>: una reposada, desbordant, complexa. De vegades equivocada, per\u00f2 igualment cr\u00edtica. I sempre vinculada a la capacitat d\u2019establir un vincle d\u2019empatia entre mestre i alumne: el primer ha de saber preguntar; el segon s&#8217;ha de sentir lliure per respondre.<\/p>\n<p>Mai\u00e8utica \u00e9s tamb\u00e9 el t\u00edtol del que \u00e9s, possiblement, un dels millors -si no el millor- <strong>disc de rock<\/strong> en espanyol del segle XXI. No \u00e9s una posici\u00f3 objectiva, \u00e9s clar, per\u00f2 em resulta dif\u00edcil pensar en un projecte m\u00e9s complex, bonic i addictiu (paradoxalment per a un disc amb can\u00e7ons de 15 minuts; de fet, hi ha qui ho considera una sola can\u00e7\u00f3 de quaranta minuts) que la simfonia de rock progressiu creada per <strong>Roberto Iniesta, \u2018Robe\u2019<\/strong>, el 2021. Un disc que continua i completa la simfonia iniciada a l&#8217;\u00e0lbum d&#8217;Extremoduro de t\u00edtol ciceroni\u00e0 <em>La Ley Innata<\/em> i que presenta, tampoc per casualitat, un cony a la portada: el part, l&#8217;inici.<\/p>\n<p><strong>S\u00f2crates, Cicer\u00f3, la mai\u00e8utica<\/strong>. Penso en tot aix\u00f2 despr\u00e9s d&#8217;haver assistit al concert de Robe Iniesta a Barcelona i comprovar, no sense una immensa joia, que els meus 47 anys no queien per res a la franja jove del p\u00fablic, com m&#8217;hauria esperat de l&#8217;experi\u00e8ncia amb Extremoduro a finals dels noranta i primers dos mil. Al rev\u00e9s. A ull, la llarga majoria dels m\u00e9s de 23.000 assistents al Parc de F\u00f2rum tenien entre 20 i 30 anys, com tamb\u00e9 van constatar les cr\u00edtiques de diaris com \u2018Ara\u2019, on se subratllava la connexi\u00f3 \u201c<em>amb un p\u00fablic molt jove, que al F\u00f2rum va cantar com nom\u00e9s es canten les can\u00e7ons que estan tocant alguna fibra molt profunda<\/em>\u201d. La majoria de l&#8217;auditori no havia nascut quan va apar\u00e8ixer <em>Agila<\/em>, i segurament moltes i molts eren filles i fills de pares i mares que havien escoltat Extremoduro al cotxe o que els havien descobert ja en plataformes digitals. La gira de Robe amb la seva excel\u00b7lent banda de m\u00fasics extremenys ha estat la m\u00e9s popular d&#8217;aquest any a Espanya, i les marees d&#8217;adolescents i postadolescents que poblaven les primeres files, les files centrals, les barres i els urinaris demostren el nivell d&#8217;intensitat brutal emocional de la connexi\u00f3 entre el vell llop plasent\u00ed de p\u00e8l ja platejat i els seus joves i gaudidors seguidors. Com tots els rituals, els concerts de m\u00fasica s\u00f3n tamb\u00e9 formes de connexi\u00f3 supraindividual.<\/p>\n<p>Penso tamb\u00e9 en tot aix\u00f2 perqu\u00e8 no som sempre conscients que moltes d&#8217;aquestes xavales i aquests xavals entregats a la poesia bruta i bella de Robe, que s&#8217;emociona fins al moll i que plora a ll\u00e0grima viva escoltant-lo, ho han passat realment malament als darrers temps, sobretot en relaci\u00f3 amb el nostre m\u00f3n, l&#8217;educatiu. Sembla que els que som ja vells haguem oblidat com va ser de dur dur la selectivitat amb mascareta, perdre&#8217;s el bo de la secund\u00e0ria o de la universitat per les mesures davant de la pand\u00e8mia, convertir-se d&#8217;un dia per al seg\u00fcent en les v\u00edctimes del frustrant pas de tot l&#8217;ecosistema educatiu primer a la metodologia del projecte, \u00e9s a dir, del <em>do-it-yourself<\/em>, el \u201c<strong>busca&#8217;t la vida<\/strong>\u201d, i despr\u00e9s del seu abandonament col\u00b7lectiu a la doc\u00e8ncia en l\u00ednia. Hi ha qui ha decidit suplantar l&#8217;empatia amb l&#8217;insult, anomenant-los amb estupideses com a \u201cgeneraci\u00f3 de vidre\u201d, com si les seves mancances no fossin les nostres, les del nostre propi sistema educatiu i social.<\/p>\n<p>Tenim molt a reflexionar i aprendre d&#8217;elles i d&#8217;ells els qui mirem la cadena tr\u00f2fica del capitalisme, si no a dalt de tot de la pir\u00e0mide, s\u00ed per descomptat en un lloc prou segur per assistir sense risc a l&#8217;esva\u00efment de les seves utopies pol\u00edtiques (des de les <em>podemitas<\/em> a les independentistes), perqu\u00e8 \u00e9s impossible alimentar utopies quan amb prou feines es poden tenir aspiracions laborals i habitacionals, amb haver sobreviscut a la davallada col\u00b7lectiva del sistema educatiu prefigurada en els darrers anys i amplificada exponencialment el 2020-2022. Cadasc\u00fa, amb la seva responsabilitat i ag\u00e8ncia, sense excloure&#8217;ns de manera autocomplaent les i els educadors. Els docents, que en comptes de preguntes empaquetem respostes, que expliquem que ja no cal aprendre. Els que moltes, massa vegades, <strong>hem renunciat a la nostra tasca de mai\u00e8utica<\/strong>.<\/p>\n<p>___<\/p>\n<p>(Nota: \u2018Merda de filosofia\u2019 \u00e9s el t\u00edtol del Segon Moviment de Mai\u00e8utica)<\/p>\n<hr \/>\n<p>Font:\u00a0<strong>educational EVIDENCE<\/strong><\/p>\n<p>Drets:\u00a0<strong>Creative Commons<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mai\u00e8utica \u00e9s di\u00e0leg. El segon acte del m\u00e8tode socr\u00e0tic d\u2019aprenentatge: el que genera el coneixement, despr\u00e9s d\u2019un primer moment de fingida ignor\u00e0ncia per part del mestre, mitjan\u00e7ant la realitzaci\u00f3 de les preguntes correctes que estimulin la recerca de les respostes dins seu.<\/p>\n","protected":false},"author":4,"featured_media":22525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"1","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[240],"tags":[2204,2208],"class_list":["post-22499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinio","tag-maieutica","tag-metode-socratic"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mai\u00e8utica (I): Merda de filosofia - Educational Evidence<\/title>\n<meta name=\"description\" content=\"La mai\u00e8utica \u00e9s di\u00e0leg. El segon acte del m\u00e8tode socr\u00e0tic d\u2019aprenentatge: el que genera el coneixement, despr\u00e9s d\u2019un primer moment de fingida ignor\u00e0ncia per part del mestre, mitjan\u00e7ant la realitzaci\u00f3 de les preguntes correctes que estimulin la recerca de les respostes dins seu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mai\u00e8utica (I): Merda de filosofia - Educational Evidence\" \/>\n<meta property=\"og:description\" content=\"La mai\u00e8utica \u00e9s di\u00e0leg. El segon acte del m\u00e8tode socr\u00e0tic d\u2019aprenentatge: el que genera el coneixement, despr\u00e9s d\u2019un primer moment de fingida ignor\u00e0ncia per part del mestre, mitjan\u00e7ant la realitzaci\u00f3 de les preguntes correctes que estimulin la recerca de les respostes dins seu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/\" \/>\n<meta property=\"og:site_name\" content=\"Educational Evidence\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T08:22:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-29T08:31:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"educational EVIDENCE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Rodrigo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/\"},\"author\":{\"name\":\"educational EVIDENCE\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#\\\/schema\\\/person\\\/91a8797f56f6a2e7ba6fd6297739bbf1\"},\"headline\":\"Mai\u00e8utica (I): Merda de filosofia\",\"datePublished\":\"2024-11-28T08:22:17+00:00\",\"dateModified\":\"2024-11-29T08:31:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/\"},\"wordCount\":904,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg\",\"keywords\":[\"mai\u00e8utica\",\"m\u00e8tode socr\u00e0tic\"],\"articleSection\":[\"Opini\u00f3\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/\",\"name\":\"Mai\u00e8utica (I): Merda de filosofia - Educational Evidence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg\",\"datePublished\":\"2024-11-28T08:22:17+00:00\",\"dateModified\":\"2024-11-29T08:31:07+00:00\",\"description\":\"La mai\u00e8utica \u00e9s di\u00e0leg. El segon acte del m\u00e8tode socr\u00e0tic d\u2019aprenentatge: el que genera el coneixement, despr\u00e9s d\u2019un primer moment de fingida ignor\u00e0ncia per part del mestre, mitjan\u00e7ant la realitzaci\u00f3 de les preguntes correctes que estimulin la recerca de les respostes dins seu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg\",\"contentUrl\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg\",\"width\":720,\"height\":638,\"caption\":\"El militar aten\u00e8s Alcib\u00edades i S\u00f2crates. \\\/ Marcello Bacciarelli \\\/ Wikimedia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/maieutica-i-merda-de-filosofia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mai\u00e8utica (I): Merda de filosofia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/\",\"name\":\"Educational Evidence\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#organization\",\"name\":\"Educational Evidence\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/educational_evidence_logo_horitzontal_blanc_negatiu.png\",\"contentUrl\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/educational_evidence_logo_horitzontal_blanc_negatiu.png\",\"width\":3508,\"height\":1090,\"caption\":\"Educational Evidence\"},\"image\":{\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/ca\\\/#\\\/schema\\\/person\\\/91a8797f56f6a2e7ba6fd6297739bbf1\",\"name\":\"educational EVIDENCE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e9888a11dc51b117a0209ebd4a5f884d.jpg?ver=1778662919\",\"url\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e9888a11dc51b117a0209ebd4a5f884d.jpg?ver=1778662919\",\"contentUrl\":\"https:\\\/\\\/educationalevidence.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e9888a11dc51b117a0209ebd4a5f884d.jpg?ver=1778662919\",\"caption\":\"educational EVIDENCE\"},\"sameAs\":[\"https:\\\/\\\/educationalevidence.com\\\/\"],\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mai\u00e8utica (I): Merda de filosofia - Educational Evidence","description":"La mai\u00e8utica \u00e9s di\u00e0leg. El segon acte del m\u00e8tode socr\u00e0tic d\u2019aprenentatge: el que genera el coneixement, despr\u00e9s d\u2019un primer moment de fingida ignor\u00e0ncia per part del mestre, mitjan\u00e7ant la realitzaci\u00f3 de les preguntes correctes que estimulin la recerca de les respostes dins seu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/","og_locale":"ca_ES","og_type":"article","og_title":"Mai\u00e8utica (I): Merda de filosofia - Educational Evidence","og_description":"La mai\u00e8utica \u00e9s di\u00e0leg. El segon acte del m\u00e8tode socr\u00e0tic d\u2019aprenentatge: el que genera el coneixement, despr\u00e9s d\u2019un primer moment de fingida ignor\u00e0ncia per part del mestre, mitjan\u00e7ant la realitzaci\u00f3 de les preguntes correctes que estimulin la recerca de les respostes dins seu.","og_url":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/","og_site_name":"Educational Evidence","article_published_time":"2024-11-28T08:22:17+00:00","article_modified_time":"2024-11-29T08:31:07+00:00","og_image":[{"width":720,"height":638,"url":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg","type":"image\/jpeg"}],"author":"educational EVIDENCE","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Javier Rodrigo","Temps estimat de lectura":"6 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/#article","isPartOf":{"@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/"},"author":{"name":"educational EVIDENCE","@id":"https:\/\/educationalevidence.com\/ca\/#\/schema\/person\/91a8797f56f6a2e7ba6fd6297739bbf1"},"headline":"Mai\u00e8utica (I): Merda de filosofia","datePublished":"2024-11-28T08:22:17+00:00","dateModified":"2024-11-29T08:31:07+00:00","mainEntityOfPage":{"@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/"},"wordCount":904,"commentCount":0,"publisher":{"@id":"https:\/\/educationalevidence.com\/ca\/#organization"},"image":{"@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/#primaryimage"},"thumbnailUrl":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg","keywords":["mai\u00e8utica","m\u00e8tode socr\u00e0tic"],"articleSection":["Opini\u00f3"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/","url":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/","name":"Mai\u00e8utica (I): Merda de filosofia - Educational Evidence","isPartOf":{"@id":"https:\/\/educationalevidence.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/#primaryimage"},"image":{"@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/#primaryimage"},"thumbnailUrl":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg","datePublished":"2024-11-28T08:22:17+00:00","dateModified":"2024-11-29T08:31:07+00:00","description":"La mai\u00e8utica \u00e9s di\u00e0leg. El segon acte del m\u00e8tode socr\u00e0tic d\u2019aprenentatge: el que genera el coneixement, despr\u00e9s d\u2019un primer moment de fingida ignor\u00e0ncia per part del mestre, mitjan\u00e7ant la realitzaci\u00f3 de les preguntes correctes que estimulin la recerca de les respostes dins seu.","breadcrumb":{"@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/#primaryimage","url":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg","contentUrl":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2024\/11\/Marcello_Bacciarelli_-_Alcibiades_Being_Taught_by_Socrates_1776-77_crop.jpg","width":720,"height":638,"caption":"El militar aten\u00e8s Alcib\u00edades i S\u00f2crates. \/ Marcello Bacciarelli \/ Wikimedia."},{"@type":"BreadcrumbList","@id":"https:\/\/educationalevidence.com\/ca\/maieutica-i-merda-de-filosofia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/educationalevidence.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Mai\u00e8utica (I): Merda de filosofia"}]},{"@type":"WebSite","@id":"https:\/\/educationalevidence.com\/ca\/#website","url":"https:\/\/educationalevidence.com\/ca\/","name":"Educational Evidence","description":"","publisher":{"@id":"https:\/\/educationalevidence.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/educationalevidence.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/educationalevidence.com\/ca\/#organization","name":"Educational Evidence","url":"https:\/\/educationalevidence.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/educationalevidence.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2023\/07\/educational_evidence_logo_horitzontal_blanc_negatiu.png","contentUrl":"https:\/\/educationalevidence.com\/wp-content\/uploads\/2023\/07\/educational_evidence_logo_horitzontal_blanc_negatiu.png","width":3508,"height":1090,"caption":"Educational Evidence"},"image":{"@id":"https:\/\/educationalevidence.com\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/educationalevidence.com\/ca\/#\/schema\/person\/91a8797f56f6a2e7ba6fd6297739bbf1","name":"educational EVIDENCE","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/educationalevidence.com\/wp-content\/litespeed\/avatar\/e9888a11dc51b117a0209ebd4a5f884d.jpg?ver=1778662919","url":"https:\/\/educationalevidence.com\/wp-content\/litespeed\/avatar\/e9888a11dc51b117a0209ebd4a5f884d.jpg?ver=1778662919","contentUrl":"https:\/\/educationalevidence.com\/wp-content\/litespeed\/avatar\/e9888a11dc51b117a0209ebd4a5f884d.jpg?ver=1778662919","caption":"educational EVIDENCE"},"sameAs":["https:\/\/educationalevidence.com\/"],"url":""}]}},"_links":{"self":[{"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/posts\/22499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/comments?post=22499"}],"version-history":[{"count":16,"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/posts\/22499\/revisions"}],"predecessor-version":[{"id":22589,"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/posts\/22499\/revisions\/22589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/media\/22525"}],"wp:attachment":[{"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/media?parent=22499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/categories?post=22499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/educationalevidence.com\/ca\/wp-json\/wp\/v2\/tags?post=22499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}